{"id":105,"count":47,"description":"","link":"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/","name":"Rabljeni ure\u0111aji","slug":"rabljeni-uredaji","taxonomy":"portfolio-category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rabljeni ure\u0111aji Archivi - Frigomec \u2013 Profesionalna oprema za restorane, barove i slasti\u010darne<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rabljeni ure\u0111aji Archivi - Frigomec \u2013 Profesionalna oprema za restorane, barove i slasti\u010darne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/\" \/>\n<meta property=\"og:site_name\" content=\"Frigomec \u2013 Profesionalna oprema za restorane, barove i slasti\u010darne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/portfolio-category\\\/rabljeni-uredaji\\\/\",\"url\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/portfolio-category\\\/rabljeni-uredaji\\\/\",\"name\":\"Rabljeni ure\u0111aji Archivi - Frigomec \u2013 Profesionalna oprema za restorane, barove i slasti\u010darne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/portfolio-category\\\/rabljeni-uredaji\\\/#breadcrumb\"},\"inLanguage\":\"hr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/portfolio-category\\\/rabljeni-uredaji\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rabljeni ure\u0111aji\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/#website\",\"url\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/\",\"name\":\"Frigomec - Fornitura e assistenza impianti alberghi e ristoranti\",\"description\":\"Pouzdana tehnologija za profesionalce u ugostiteljstvu\",\"publisher\":{\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/#organization\",\"name\":\"Frigomec - Fornitura e assistenza impianti alberghi e ristoranti\",\"url\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/frigomec.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-frigomec.png\",\"contentUrl\":\"https:\\\/\\\/frigomec.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-frigomec.png\",\"width\":516,\"height\":516,\"caption\":\"Frigomec - Fornitura e assistenza impianti alberghi e ristoranti\"},\"image\":{\"@id\":\"https:\\\/\\\/frigomec.it\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Frigomec1?fref=ts\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rabljeni ure\u0111aji Archivi - Frigomec \u2013 Profesionalna oprema za restorane, barove i slasti\u010darne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/","og_locale":"hr_HR","og_type":"article","og_title":"Rabljeni ure\u0111aji Archivi - Frigomec \u2013 Profesionalna oprema za restorane, barove i slasti\u010darne","og_url":"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/","og_site_name":"Frigomec \u2013 Profesionalna oprema za restorane, barove i slasti\u010darne","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/","url":"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/","name":"Rabljeni ure\u0111aji Archivi - Frigomec \u2013 Profesionalna oprema za restorane, barove i slasti\u010darne","isPartOf":{"@id":"https:\/\/frigomec.it\/hr\/#website"},"breadcrumb":{"@id":"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/#breadcrumb"},"inLanguage":"hr"},{"@type":"BreadcrumbList","@id":"https:\/\/frigomec.it\/hr\/portfolio-category\/rabljeni-uredaji\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/frigomec.it\/hr\/"},{"@type":"ListItem","position":2,"name":"Rabljeni ure\u0111aji"}]},{"@type":"WebSite","@id":"https:\/\/frigomec.it\/hr\/#website","url":"https:\/\/frigomec.it\/hr\/","name":"Frigomec - Fornitura e assistenza impianti alberghi e ristoranti","description":"Pouzdana tehnologija za profesionalce u ugostiteljstvu","publisher":{"@id":"https:\/\/frigomec.it\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frigomec.it\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hr"},{"@type":"Organization","@id":"https:\/\/frigomec.it\/hr\/#organization","name":"Frigomec - Fornitura e assistenza impianti alberghi e ristoranti","url":"https:\/\/frigomec.it\/hr\/","logo":{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/frigomec.it\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/frigomec.it\/wp-content\/uploads\/2024\/04\/logo-frigomec.png","contentUrl":"https:\/\/frigomec.it\/wp-content\/uploads\/2024\/04\/logo-frigomec.png","width":516,"height":516,"caption":"Frigomec - Fornitura e assistenza impianti alberghi e ristoranti"},"image":{"@id":"https:\/\/frigomec.it\/hr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Frigomec1?fref=ts"]}]}},"_links":{"self":[{"href":"https:\/\/frigomec.it\/hr\/wp-json\/wp\/v2\/portfolio-category\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frigomec.it\/hr\/wp-json\/wp\/v2\/portfolio-category"}],"about":[{"href":"https:\/\/frigomec.it\/hr\/wp-json\/wp\/v2\/taxonomies\/portfolio-category"}],"wp:post_type":[{"href":"https:\/\/frigomec.it\/hr\/wp-json\/wp\/v2\/portfolio?portfolio-category=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}